{"id":873,"date":"2024-10-24T16:58:44","date_gmt":"2024-10-24T16:58:44","guid":{"rendered":"https:\/\/munbaexpeditions.mx\/?page_id=873"},"modified":"2025-01-27T16:53:59","modified_gmt":"2025-01-27T16:53:59","slug":"aviso-de-privacidad","status":"publish","type":"page","link":"https:\/\/munbaexpeditions.mx\/en\/aviso-de-privacidad\/","title":{"rendered":"Privacy Notice"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"873\" class=\"elementor elementor-873\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a66ca31 e-flex e-con-boxed e-con e-parent\" data-id=\"a66ca31\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bbace40 e-con-full e-flex e-con e-child\" data-id=\"bbace40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0af03c2 elementor-widget elementor-widget-image\" data-id=\"0af03c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/en\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"659\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/uploads\/2024\/11\/Logo-Blanco.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1390\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbb791 elementor-mobile-align-right elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"3fbb791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/munbaexpeditions.mx\/boletos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Boletos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67a7daa e-con-full e-flex e-con e-child\" data-id=\"67a7daa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82d763b elementor-nav-menu__align-start elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"82d763b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-slide\">\n\t\t\t\t<ul id=\"menu-1-82d763b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-161\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/\" class=\"elementor-item\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-162\"><a href=\"https:\/\/munbaexpeditions.mx\/#quienessomos\" class=\"elementor-item elementor-item-anchor\">Quienes Somos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-163\"><a href=\"https:\/\/munbaexpeditions.mx\/#atracciones\" class=\"elementor-item elementor-item-anchor\">Atracciones<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-173\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/contacto\/\" class=\"elementor-item\">Contacto<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-665\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-470\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/es_MX.png\" width=\"18\" height=\"12\" alt=\"es_MX\" title=\"Spanish\"><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-468\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"French\"><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open  ti-menu\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close  ti-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-82d763b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-161\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/\" class=\"elementor-item\" tabindex=\"-1\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-162\"><a href=\"https:\/\/munbaexpeditions.mx\/#quienessomos\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Quienes Somos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-163\"><a href=\"https:\/\/munbaexpeditions.mx\/#atracciones\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Atracciones<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-173\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/contacto\/\" class=\"elementor-item\" tabindex=\"-1\">Contacto<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-665\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-470\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/es_MX.png\" width=\"18\" height=\"12\" alt=\"es_MX\" title=\"Spanish\"><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-468\"><a href=\"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\"><span data-no-translation><img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"French\"><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ab32cf e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"9ab32cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1de7fa0 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"1de7fa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/munbaexpeditions.mx\/boletos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Boletos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d84088 e-flex e-con-boxed e-con e-parent\" data-id=\"3d84088\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7ac0b0 elementor-widget elementor-widget-spacer\" data-id=\"e7ac0b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf71fee e-flex e-con-boxed e-con e-parent\" data-id=\"cf71fee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-459fc52 elementor-widget elementor-widget-spacer\" data-id=\"459fc52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2166bd elementor-widget elementor-widget-text-editor\" data-id=\"f2166bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><strong><b>Aviso de privacidad<\/b><\/strong><\/h1>\n<p>En <strong><b>\u201cMAZALIFE\/CITY TOURS\u201d <\/b><\/strong>propiedad de<strong><b>&nbsp;Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V , <\/b><\/strong>su privacidad y confianza son muy importantes; por ello, queremos asegurarnos de que nuestros beneficiados, usuarios patrocinadores y proveedores conozcan c\u00f3mo salvaguardamos la integridad, privacidad y protecci\u00f3n de sus datos personales conforme a lo previsto en la Ley Federal de Protecci\u00f3n de Datos Personales en Posesi\u00f3n de los Particulares (la &#8220;Ley&#8221;).<\/p>\n<p><strong><b>Sobre la Empresa:<\/b><\/strong><\/p>\n<p><strong><b>Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V <\/b><\/strong>con domicilio en Calle Angel Flores n\u00famero 604, Colonia Centro, C\u00f3digo Postal 82000 Mazatl\u00e1n, Sinaloa y quien es propietaria de <strong><b>\u201c<\/b><\/strong><strong><b>MAZALIFE\/CITY TOURS\u201d<\/b><\/strong>&nbsp;declara en relaci\u00f3n al manejo de los datos personales lo siguiente:<\/p>\n<ol>\n<li><b><\/b><strong><b>CONTENIDO DE LOS DATOS PERSONALES.<\/b><\/strong><\/li>\n<\/ol>\n<p>De acuerdo con la Ley, se entienden como \u201cDatos Personales\u201d cualquier informaci\u00f3n alusiva a una persona f\u00edsica o moral identificada o identificable. Para efectos del presente Aviso de Privacidad, de manera enunciativa m\u00e1s no limitativa, se entender\u00e1n como \u201cDatos Personales\u201d:<\/p>\n<ol>\n<li>a) Datos generales: Nombre de la Persona Moral, Nombre del apoderado o Representante legal, Nombre (s) y apellidos, fecha de nacimiento, sexo, estado civil, existencia o no de hijos, domicilio, tel\u00e9fono fijo (de casa u oficina), tel\u00e9fono celular, correo electr\u00f3nico, Registro Federal de Causantes (RFC), Clave \u00danica de Registro Poblacional (CURP), r\u00e9gimen fiscal, especificaci\u00f3n sobre formas de pago (efectivo, vales, cheques, cuentas bancarias, dep\u00f3sitos y\/o visas), n\u00famero de folio de Credencial de Elector (IFE), entre otros datos similares concernientes a una persona.<\/li>\n<\/ol>\n<ol>\n<li>b) Datos personales sensibles: Se consideran datos personales sensibles, informaci\u00f3n de: origen racial o \u00e9tnico, estado de salud presente y futura, informaci\u00f3n gen\u00e9tica, creencias religiosas, filos\u00f3ficas y morales, afiliaci\u00f3n sindical, opiniones pol\u00edticas, preferencia sexual.<\/li>\n<\/ol>\n<p>Para cumplir con las finalidades previstas en este aviso, en caso de ser recabados datos personales de este tipo, estos ser\u00e1n tratados bajo medidas de seguridad, siempre garantizando su confidencialidad.<\/p>\n<p>Si usted no manifiesta su oposici\u00f3n mediante la&nbsp;<a style=\"color: blue;\" href=\"https:\/\/munbaexpeditions.mx\/wp-content\/uploads\/2024\/10\/FORMATO_DE_SOLICITUD_PARA_EL_EJERCICIO_DE_LOS_DERECHOS_ARCO_MAZA.pdf\" target=\"_blank\" rel=\"noopener\">solicitud de revocaci\u00f3n para los derechos ARCO<\/a>, se entender\u00e1 que ha otorgado su consentimiento para la recopilaci\u00f3n de dichos datos en los t\u00e9rminos aqu\u00ed se\u00f1alados.<\/p>\n<p>Consentimiento: \u201cAl recibir este aviso, manifiesto mi voluntad como titular de los datos, para que <strong><b>\u201cMAZALIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>efect\u00fae el tratamiento de los mismos, entendiendo como tratamiento la obtenci\u00f3n, uso, divulgaci\u00f3n o almacenamiento de datos personales, por cualquier medio. El uso abarca cualquier acci\u00f3n de acceso, manejo, aprovechamiento, transferencia o disposici\u00f3n de mis datos personales&#8221;.<\/p>\n<ol>\n<li>c) Datos relacionados con solicitudes de empleo: Cuando se ingresen o proporcionen Datos Personales en la bolsa de trabajo de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d<\/b><\/strong>, adem\u00e1s de los datos generales, se considerar\u00e1n Datos Personales la informaci\u00f3n sobre nivel educativo, experiencia laboral y cualquier informaci\u00f3n relacionada con la solicitud de empleo llenada o el curr\u00edculo que sea entregado o enviado.<\/li>\n<\/ol>\n<ol>\n<li>d) Revistas y transacciones en l\u00ednea: Cuando el usuario se suscriba para recibir alguno de los productos de <strong><b>\u201cMAZALIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d ,<\/b><\/strong>tales como publicidad impresa (revistas, boletines, folletos, etc.), boletines electr\u00f3nicos, entre otros y cuando se realicen transacciones de donativos y servicios en cualquiera de nuestras plataformas digitales, aplicaciones, actuales o futuras, adem\u00e1s de los datos generales, se consideraran Datos Personales los relacionados con tarjetas bancarias tales como nombre del tarjetahabiente, n\u00famero de tarjeta, fecha de vencimiento de la tarjeta, tipo de tarjeta, c\u00f3digo de seguridad, adem\u00e1s del domicilio de entrega del producto y cualquier otra informaci\u00f3n y cualquier informaci\u00f3n necesaria para la suscripci\u00f3n o transacci\u00f3n en l\u00ednea.<\/li>\n<\/ol>\n<p>Los Datos Personales referidos en este punto \u00fanicamente estar\u00e1n sujetos a las Finalidades del Tratamiento establecidas m\u00e1s adelante en el presente Aviso de Privacidad, por el tiempo que dure la transacci\u00f3n comercial; es decir, una vez que la transacci\u00f3n y sus efectos concluyan, los Datos Personales ser\u00e1n eliminados de nuestras bases de datos.<\/p>\n<p>Los Datos personales mencionados en los incisos a, b y c arriba expuestos y correspondientes al presente Aviso de Privacidad, ser\u00e1n recabados mediante el llenado de los formatos y\/o mediante la recopilaci\u00f3n de informaci\u00f3n o documentaci\u00f3n requerida por <strong><b>\u201cMAZALIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d <\/b><\/strong>&nbsp;ya sea de manera personal o v\u00eda electr\u00f3nica a trav\u00e9s de las p\u00e1ginas de internet oficial de la empresa.<\/p>\n<ol>\n<li>e) Redes Sociales: Las redes sociales (tales como Facebook, Twitter, Instagram, Foursquare, Linked In, entre otras), son una plataforma de comunicaci\u00f3n e interconexi\u00f3n dentro de plataformas digitales de los diferentes usuarios, son ajenas a <strong><b>\u201cMAZA LIFE\/CITY TOURS\/\/Operadora Turistica Observatorio 1873 S.A. de C.V.<\/b><\/strong>y, por lo tanto, no se encuentran bajo su responsabilidad.<\/li>\n<\/ol>\n<p>La informaci\u00f3n que se proporcione a las redes sociales en las que <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.<\/b><\/strong>&nbsp;participa como usuario, no forma parte de los Datos Personales sujetos a la protecci\u00f3n de este Aviso de Privacidad, siendo responsabilidad de la empresa prestadora de esa plataforma y de qui\u00e9n lo publica.<\/p>\n<ol>\n<li>f) Cookies: Las Cookies son archivos de texto que se descargan autom\u00e1ticamente y se almacenan en el disco duro del equipo de c\u00f3mputo del usuario al navegar en una p\u00e1gina o portal de Internet espec\u00edfico, que permiten almacenar al servidor de Internet ciertos datos, entre ellos, p\u00e1ginas preferidas de visualizaci\u00f3n en internet, algunas claves y contrase\u00f1as.<\/li>\n<\/ol>\n<p><strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d <\/b><\/strong>&nbsp;utilizar\u00e1 cookies para determinar sus preferencias cuando se conecta a los servicios de nuestro sitio. Por lo anteriormente dicho, a partir de este momento, el usuario otorga su consentimiento a <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d <\/b><\/strong>para mantener en sus registros tanto f\u00edsicos como electr\u00f3nicos, toda la informaci\u00f3n que nos haya sido facilitada a trav\u00e9s de cualquier medio de los puestos a disposici\u00f3n por <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d &nbsp;<\/b><\/strong>a fin de recabar sus Datos Personales.<\/p>\n<p>La confidencialidad y seguridad de los datos que los usuarios proporcionen al solicitar un servicio o comprar un producto en l\u00ednea, estar\u00e1n protegidos con un candado SSL (Secure Socket Layer) de VeriSign;&nbsp;de tal forma que los datos proporcionados se transmitir\u00e1n encriptados para asegurar su resguardo.<\/p>\n<p>Sin embargo, el usuario y\/o patrocinadores y proveedores de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>entienden y aceptan que los mecanismos de seguridad para la informaci\u00f3n que viaja por Internet podr\u00edan tener errores y fallas que escapan del control de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.<\/b><\/strong>&nbsp;&nbsp;y que por ser el Internet un medio de libre acceso al p\u00fablico en general pudiera ser vulnerable de delitos inform\u00e1ticos por parte de terceros sin responsabilidad para <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d<\/b><\/strong><\/p>\n<ol>\n<li><strong><b> SOBRE LA PERSONA RESPONSABLE DE RECABAR DATOS PERSONALES<\/b><\/strong><\/li>\n<\/ol>\n<p>Se declara que sus datos personales estar\u00e1n a cargo de Jorge Luis Camacho Peinado quien es el \u00fanico responsable del tratamiento de los mismos, con correo electr\u00f3nico&nbsp; contraloria@petroil.com.mx y con domicilio en&nbsp;Calle Angel Flores n\u00famero 604, Colonia Centro, C\u00f3digo Postal 82000 Mazatl\u00e1n, Sinaloa<\/p>\n<p><strong><b>III. TRATAMIENTO DE DATOS PERSONALES<\/b><\/strong><\/p>\n<p>Se considera \u201cTratamiento de Datos Personales\u201d la obtenci\u00f3n, uso, divulgaci\u00f3n o almacenamiento de Datos Personales por cualquier medio. El uso se extienda a cualquier actividad de acceso, manejo, aprovechamiento, transferencia o disposici\u00f3n de Datos Personales.<\/p>\n<p>El Tratamiento de Datos Personales por parte de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d ,<\/b><\/strong>&nbsp;se sujetar\u00e1 a lo dispuesto en el siguiente punto.<\/p>\n<ol>\n<li><strong><b> FINALIDADES DEL TRATAMIENTO DE DATOS PERSONALES<\/b><\/strong><\/li>\n<\/ol>\n<p>A trav\u00e9s del presente Aviso de Privacidad, <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V., <\/b><\/strong>declara que las finalidades del tratamiento de sus Datos Personales ser\u00e1n los siguientes (\u201cFinalidades del Tratamiento\u201d):<\/p>\n<ol>\n<li>a) Fines informativos: con el objeto de dar a conocer la informaci\u00f3n y labor comercial de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d<\/b><\/strong><\/li>\n<\/ol>\n<ol>\n<li>b) Investigaci\u00f3n y diversos estudios de mercado: cuestionarios y entrevistas.<\/li>\n<\/ol>\n<ol>\n<li>e) Reclutamiento y selecci\u00f3n de personal, en caso de que el usuario aplique a alguna de las vacantes de la bolsa de trabajo de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d <\/b><\/strong>y reciba informaci\u00f3n sobre ofertas de empleo o vacantes que surjan al interior de la empresa.<\/li>\n<\/ol>\n<p>En caso de que se pretenda tratar los Datos Personales de los usuarios para un fin distinto al expresado en el presente Aviso de Privacidad, <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d &nbsp;<\/b><\/strong>deber\u00e1 obtener el consentimiento del usuario para tal fin de nueva cuenta.<\/p>\n<ol>\n<li><strong><b> ACEPTACI\u00d3N DEL TRATAMIENTO DE DATOS PERSONALES<\/b><\/strong><\/li>\n<\/ol>\n<p>Los datos personales que usted ha proporcionado directamente o a trav\u00e9s de medios electr\u00f3nicos a <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>han sido recabados y ser\u00e1n tratados por <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.<\/b><\/strong>&nbsp;bajo los principios de licitud, consentimiento, informaci\u00f3n, calidad, finalidad, lealtad y responsabilidad de conformidad con lo dispuesto por la Ley.<\/p>\n<ol>\n<li><strong><b> LIMITACIONES DE USO DE DATOS PERSONALES<\/b><\/strong><\/li>\n<\/ol>\n<p>En caso de que el Titular desee limitar el uso de sus Datos Personales, en relaci\u00f3n con una o varias de las finalidades del Tratamiento de Datos Personales (por ejemplo, correos publicitarios, felicitaciones de cumplea\u00f1os, investigaciones de mercado, entre otros), podr\u00e1 enviar la solicitud correspondiente conforme al proceso estipulado en el punto VII del presente Aviso de Privacidad.<\/p>\n<p><strong><b>VII. DERECHOS DE ACCESO, RECTIFICACI\u00d3N, CANCELACI\u00d3N U OPOSICI\u00d3N. (DERECHOS ARCO)<\/b><\/strong><\/p>\n<p>De acuerdo a lo establecido en la Ley, el Titular tiene derecho al acceso, rectificaci\u00f3n cancelaci\u00f3n u oposici\u00f3n al Tratamiento de sus Datos Personales para cual se deber\u00e1 seguir el siguiente procedimiento:<\/p>\n<ol>\n<li>a) Como Titular de Datos Personales, presentar o enviar una <a style=\"color: blue;\" href=\"https:\/\/munbaexpeditions.mx\/wp-content\/uploads\/2024\/10\/FORMATO_DE_SOLICITUD_PARA_EL_EJERCICIO_DE_LOS_DERECHOS_ARCO_MAZA.pdf\" target=\"_blank\" rel=\"noopener\">solicitud para el acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n<\/a> al correo contraloria@petroil.com.mx dirigida al responsable del tratamiento de sus datos.<\/li>\n<\/ol>\n<ol>\n<li>b) Resoluci\u00f3n y comunicaci\u00f3n <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>comunicar\u00e1 al Titular de los Datos Personales la determinaci\u00f3n adoptada en un plazo no mayor a 15 d\u00edas h\u00e1biles, a partir de la fecha en que se recibi\u00f3 la solicitud. Este plazo podr\u00e1 ser ampliado por <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>en una sola ocasi\u00f3n por un periodo igual, siempre y cuando as\u00ed lo justifiquen las circunstancias del caso.<\/li>\n<\/ol>\n<p>De acuerdo a lo establecido en la Ley, <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>informar\u00e1 al Titular de los Datos Personales la resoluci\u00f3n tomada por el mismo medio por el que se llev\u00f3 a cabo la solicitud acompa\u00f1ando a la misma con las pruebas pertinentes en su caso.<\/p>\n<p>Cuando la resoluci\u00f3n sea procedente, se har\u00e1 efectiva por <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>en los siguientes 15 d\u00edas a la comunicaci\u00f3n de la resoluci\u00f3n hecha.<\/p>\n<p>El titular podr\u00e1 presentar ante el Instituto Nacional de Acceso a la Informaci\u00f3n (INAI) una solicitud de protecci\u00f3n de datos por la respuesta recibida o falta de respuesta de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>dentro de los 15 d\u00edas h\u00e1biles siguientes a la fecha en que se comunique la respuesta al titular por parte de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>y se sujetar\u00e1 a lo previsto en la Ley.<\/p>\n<p>En caso de solicitudes de acceso a Datos Personales, ser\u00e1 necesario que el solicitante o su representante legal acrediten previamente su identidad.<\/p>\n<p>La obligaci\u00f3n de acceso a la informaci\u00f3n se dar\u00e1 por cumplida cuando <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>ponga a disposici\u00f3n del titular los Datos Personales o mediante la expedici\u00f3n de copias simples o documentos electr\u00f3nicos.<\/p>\n<p>En el supuesto en que una persona solicite a <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>el acceso a sus Datos Personales presumiendo que \u00e9ste es el responsable y resultara que no lo es, bastar\u00e1 con que <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>as\u00ed se lo indique al titular por los medios de establecidos en este apartado, para tener por desahogada la solicitud.<\/p>\n<p>La contestaci\u00f3n de la solicitud para acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n de los Datos Personales ser\u00e1 gratuita. En caso de solicitar env\u00edo de copias u otros formatos, los gastos derivados de los mismos deber\u00e1n ser cubiertos por el Titular, costos que en su momento, <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>informar\u00e1 oportunamente a quien corresponda.<\/p>\n<ol>\n<li>c) Negativa para acceder a Datos Personales: <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>podr\u00e1 negar el acceso total o parcial a los Datos Personales o a la realizaci\u00f3n de la rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n al tratamiento de los mismos, en los siguientes casos:<\/li>\n<\/ol>\n<p>-Cuando el solicitante no sea el titular o el representante legal no est\u00e9 acreditado para ello.<\/p>\n<p>-Cuando en la Base de Datos de <strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>no se encuentren los Datos Personales del solicitante.<\/p>\n<p>-Cuando se lesionen los derechos de un tercero.<\/p>\n<p>-Cuando exista impedimento legal o resoluci\u00f3n de una autoridad.<\/p>\n<p>-Cuando la rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n haya sido previamente realizada, de manera que la solicitud carezca de materia.<\/p>\n<p><strong><b>VIII. TRANSFERENCIA DE DATOS<\/b><\/strong><\/p>\n<p><strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>no realiza transferencias de sus datos a terceros nacionales o extranjeros. Se informa que sus datos personales, incluyendo sus datos sensibles.<\/p>\n<p><strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V. <\/b><\/strong>se reserva el derecho de efectuar en cualquier momento modificaciones o actualizaciones al presente Aviso de Privacidad, para atenci\u00f3n de novedades legislativas o jurisprudenciales, pol\u00edticas internas, nuevos requerimientos para la prestaci\u00f3n u ofrecimiento de nuestros servicios o productos y pr\u00e1cticas del mercado.<\/p>\n<p>Estas modificaciones estar\u00e1n disponibles al p\u00fablico a trav\u00e9s nuestra p\u00e1gina de internet: <a href=\"https:\/\/munbaexpeditions.mx\/\">https:\/\/munbaexpeditions.mx\/<\/a><\/p>\n<p>Es responsabilidad del Titular revisar el contenido actualizado del aviso de privacidad disponible en la p\u00e1gina de Internet <a href=\"https:\/\/munbaexpeditions.mx\/aviso-de-privacidad\">https:\/\/munbaexpeditions.mx\/aviso-de-privacidad<\/a><\/p>\n<p><strong><b>\u201cMAZA LIFE\/CITY TOURS\/Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V.\u201d <\/b><\/strong>&nbsp;&nbsp;asume que si el Titular no se opone a los cambios informando oportunamente a trav\u00e9s de alguno de los medios expuestos en el inciso a del punto VI de este documento, significa que ha le\u00eddo, entendido y consentido los t\u00e9rminos aqu\u00ed establecidos.<\/p>\n<ol>\n<li><strong><b> QUEJAS Y DENUNCIAS POR EL TRATAMIENTO INDEBIDO DE SUS DATOS PERSONALES<\/b><\/strong><\/li>\n<\/ol>\n<p>Si usted considera que su derecho de protecci\u00f3n de datos personales ha sido lesionado por alguna conducta de nuestros empleados o de nuestras actuaciones o respuestas, presume que en el tratamiento de sus datos personales existe alguna violaci\u00f3n a las disposiciones previstas en la Ley Federal de Protecci\u00f3n de Datos Personales en Posesi\u00f3n de los Particulares, podr\u00e1 interponer la queja o denuncia correspondiente ante el INAI, para mayor informaci\u00f3n visite <a href=\"https:\/\/home.inai.org.mx\/\">https:\/\/home.inai.org.mx\/<\/a><\/p>\n<p>El presente Aviso de Privacidad fue actualizado por \u00faltima ocasi\u00f3n el 17 &nbsp;de OCTUBRE de 2024.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e8ecc5 e-flex e-con-boxed e-con e-parent\" data-id=\"6e8ecc5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4026f7c elementor-widget elementor-widget-spacer\" data-id=\"4026f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42bbc3e e-flex e-con-boxed e-con e-parent\" data-id=\"42bbc3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2280e59 e-con-full e-flex e-con e-child\" data-id=\"2280e59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7388202 elementor-widget elementor-widget-image\" data-id=\"7388202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"659\" src=\"https:\/\/munbaexpeditions.mx\/wp-content\/uploads\/2024\/11\/Logo-Blanco.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1390\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4fe65e elementor-widget elementor-widget-heading\" data-id=\"a4fe65e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Aventuras emocionantes, vistas impresionantes y momentos inolvidables en Mazatl\u00e1n, combinando diversi\u00f3n, cultura y naturaleza.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32940bc e-grid-align-left e-grid-align-mobile-center elementor-shape-circle e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"32940bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-pop elementor-repeater-item-ce27b21\" href=\"https:\/\/www.youtube.com\/@MazalifeTourism\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-pop elementor-repeater-item-9585a0e\" href=\"https:\/\/www.instagram.com\/mazalifetourism\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-animation-pop elementor-repeater-item-f93cdf6\" href=\"https:\/\/www.tiktok.com\/@mazalife.tourism?lang=es\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-tiktok\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448,209.91a210.06,210.06,0,0,1-122.77-39.25V349.38A162.55,162.55,0,1,1,185,188.31V278.2a74.62,74.62,0,1,0,52.23,71.18V0l88,0a121.18,121.18,0,0,0,1.86,22.17h0A122.18,122.18,0,0,0,381,102.39a121.43,121.43,0,0,0,67,20.14Z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-pop elementor-repeater-item-adf19db\" href=\"https:\/\/www.facebook.com\/MazalifeTourism\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39458f5 e-con-full e-flex e-con e-child\" data-id=\"39458f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfbaa38 elementor-widget elementor-widget-heading\" data-id=\"cfbaa38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Atracciones<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04942de elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"04942de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/observatorio1873.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Observatorio 1873<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munba.mx\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Munba <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/shekinahbeachclub.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Shekinah<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lamansionpirata.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mansi\u00f3n Pirata<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Helimaz <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0a0485 e-con-full e-flex e-con e-child\" data-id=\"e0a0485\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d17233 elementor-widget elementor-widget-heading\" data-id=\"7d17233\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Nosotros <\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a23ea elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c8a23ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/#quienessomos\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quienes Somos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/#atracciones\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Atracciones<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/boletos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Boletos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/puntos-de-venta-fisicos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Punto de Venta <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/contacto\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contacto <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f8d733 e-con-full e-flex e-con e-child\" data-id=\"2f8d733\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3623ffa elementor-widget elementor-widget-heading\" data-id=\"3623ffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Ponte en contacto<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3ad997 elementor-view-stacked elementor-position-inline-start elementor-mobile-position-inline-start elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"a3ad997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:(669)%20260%2098%2044\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Hablemos\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:(669)%20260%2098%2044\" >\n\t\t\t\t\t\t\tHablemos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t+52 (669) 454 0031\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2a09f elementor-view-stacked elementor-position-inline-start elementor-mobile-position-inline-start elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"6e2a09f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"mailto:hola@mazalife.com.mx\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Envianos un Correo\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"mailto:hola@mazalife.com.mx\" >\n\t\t\t\t\t\t\tEnvianos un Correo\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\thola@munbaexpeditions.mx\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63909d5 e-flex e-con-boxed e-con e-child\" data-id=\"63909d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52b1d4b elementor-widget elementor-widget-heading\" data-id=\"52b1d4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Copyright \u00a9 2024 Mazalife, Todos los derechos reservados. Powered by Quetzaltic <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1af4d7c elementor-align-end elementor-icon-list--layout-inline elementor-tablet-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1af4d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/aviso-de-privacidad\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aviso de Privacidad<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/munbaexpeditions.mx\/terminos-y-condiciones\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00e9rminos y Condiciones<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Boletos Boletos Aviso de privacidad En \u201cMAZALIFE\/CITY TOURS\u201d propiedad de&nbsp;Operadora Tur\u00edstica Observatorio 1873 S.A. de C.V , su privacidad y confianza son muy importantes; por ello, queremos asegurarnos de que nuestros beneficiados, usuarios patrocinadores y proveedores conozcan c\u00f3mo salvaguardamos la integridad, privacidad y protecci\u00f3n de sus datos personales conforme a lo previsto en la Ley [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-873","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/comments?post=873"}],"version-history":[{"count":5,"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873\/revisions"}],"predecessor-version":[{"id":1631,"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/pages\/873\/revisions\/1631"}],"wp:attachment":[{"href":"https:\/\/munbaexpeditions.mx\/en\/wp-json\/wp\/v2\/media?parent=873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}